{"id":113,"count":42,"description":"","link":"https:\/\/feinschmeckergarten.de\/index.php\/tag\/rezept\/","name":"Rezept","slug":"rezept","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/feinschmeckergarten.de\/index.php\/wp-json\/wp\/v2\/tags\/113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feinschmeckergarten.de\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/feinschmeckergarten.de\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/feinschmeckergarten.de\/index.php\/wp-json\/wp\/v2\/posts?tags=113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}